{"id":3285,"date":"2023-10-09T21:40:35","date_gmt":"2023-10-09T21:40:35","guid":{"rendered":"https:\/\/staging.wearensn.com\/?post_type=team&#038;p=3285"},"modified":"2024-05-29T08:42:35","modified_gmt":"2024-05-29T08:42:35","slug":"toni-vilalta","status":"publish","type":"team","link":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/","title":{"rendered":"Toni Vilalta"},"content":{"rendered":"","protected":false},"featured_media":7766,"template":"","class_list":["post-3285","team","type-team","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toni Vilalta - We Are NSN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toni Vilalta - We Are NSN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/\" \/>\n<meta property=\"og:site_name\" content=\"We Are NSN\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-29T08:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/10\/nsn-toni-vilalta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"951\" \/>\n\t<meta property=\"og:image:height\" content=\"1168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/\",\"url\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/\",\"name\":\"Toni Vilalta - We Are NSN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wearensn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/nsn-toni-vilalta.jpg\",\"datePublished\":\"2023-10-09T21:40:35+00:00\",\"dateModified\":\"2024-05-29T08:42:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wearensn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/nsn-toni-vilalta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wearensn.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/nsn-toni-vilalta.jpg\",\"width\":951,\"height\":1168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/team\\\/toni-vilalta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Toni Vilalta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/\",\"name\":\"We Are NSN\",\"description\":\"Sports &amp; Entertainment\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#organization\",\"name\":\"We Are NSN\",\"url\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wearensn.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Favicon-never-say-never.png\",\"contentUrl\":\"https:\\\/\\\/www.wearensn.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/cropped-Favicon-never-say-never.png\",\"width\":512,\"height\":512,\"caption\":\"We Are NSN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wearensn.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toni Vilalta - We Are NSN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/","og_locale":"ja_JP","og_type":"article","og_title":"Toni Vilalta - We Are NSN","og_url":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/","og_site_name":"We Are NSN","article_modified_time":"2024-05-29T08:42:35+00:00","og_image":[{"width":951,"height":1168,"url":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/10\/nsn-toni-vilalta.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/","url":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/","name":"Toni Vilalta - We Are NSN","isPartOf":{"@id":"https:\/\/www.wearensn.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/#primaryimage"},"image":{"@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/10\/nsn-toni-vilalta.jpg","datePublished":"2023-10-09T21:40:35+00:00","dateModified":"2024-05-29T08:42:35+00:00","breadcrumb":{"@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/#primaryimage","url":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/10\/nsn-toni-vilalta.jpg","contentUrl":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/10\/nsn-toni-vilalta.jpg","width":951,"height":1168},{"@type":"BreadcrumbList","@id":"https:\/\/www.wearensn.com\/ja\/team\/toni-vilalta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wearensn.com\/ja\/"},{"@type":"ListItem","position":2,"name":"Toni Vilalta"}]},{"@type":"WebSite","@id":"https:\/\/www.wearensn.com\/ja\/#website","url":"https:\/\/www.wearensn.com\/ja\/","name":"We Are NSN","description":"Sports &amp; Entertainment","publisher":{"@id":"https:\/\/www.wearensn.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wearensn.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/www.wearensn.com\/ja\/#organization","name":"We Are NSN","url":"https:\/\/www.wearensn.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/www.wearensn.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/08\/cropped-Favicon-never-say-never.png","contentUrl":"https:\/\/www.wearensn.com\/wp-content\/uploads\/2023\/08\/cropped-Favicon-never-say-never.png","width":512,"height":512,"caption":"We Are NSN"},"image":{"@id":"https:\/\/www.wearensn.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.wearensn.com\/ja\/wp-json\/wp\/v2\/team\/3285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wearensn.com\/ja\/wp-json\/wp\/v2\/team"}],"about":[{"href":"https:\/\/www.wearensn.com\/ja\/wp-json\/wp\/v2\/types\/team"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wearensn.com\/ja\/wp-json\/wp\/v2\/media\/7766"}],"wp:attachment":[{"href":"https:\/\/www.wearensn.com\/ja\/wp-json\/wp\/v2\/media?parent=3285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}